
{"id":123058,"date":"2026-04-20T10:41:26","date_gmt":"2026-04-20T08:41:26","guid":{"rendered":"https:\/\/inmosolycasas.com\/?post_type=property&#038;p=123058"},"modified":"2026-04-20T10:50:28","modified_gmt":"2026-04-20T08:50:28","slug":"chalet-el-planet-benidorm","status":"publish","type":"property","link":"https:\/\/inmosolycasas.com\/es\/property\/chalet-el-planet-benidorm\/","title":{"rendered":"Chalet El planet Benidorm"},"content":{"rendered":"<p>Chalet El Planet Benidorm<\/p>\n<p>Esta exclusiva propiedad cuenta con una superficie habitable de 982 m\u00b2 en una generosa parcela de 2.618 m\u00b2. El precioso jard\u00edn incluye \u00e1rboles frutales, un peque\u00f1o huerto y una espaciosa piscina, ideal para relajarse y disfrutar del aire libre.<\/p>\n<p>Disfrute del lujo viviendo en esta imponente villa con impresionantes vistas al mar y a la monta\u00f1a, ubicada en las afueras de Benidorm.<\/p>\n<p>Al entrar en la planta baja, encontrar\u00e1 un luminoso vest\u00edbulo que conduce a un amplio sal\u00f3n-comedor con acceso directo a la terraza. Adem\u00e1s, en esta planta se encuentra una moderna cocina con lavadero, un dormitorio con ba\u00f1o en suite, un segundo dormitorio y un aseo independiente.<\/p>\n<p>En la primera planta, se encuentra un espacioso dormitorio principal con vestidor, un lujoso ba\u00f1o y una gran terraza con vistas panor\u00e1micas al mar y a la monta\u00f1a. Adem\u00e1s, hay cuatro dormitorios m\u00e1s y dos ba\u00f1os.<\/p>\n<p>La planta superior ofrece una amplia sala multiusos con acceso a una terraza, perfecta como dormitorio adicional, despacho o sala de estar. En el s\u00f3tano (aprox. 300 m\u00b2), con entrada privada, se encuentra un espacio totalmente independiente. Actualmente, est\u00e1 configurado como seis oficinas cerradas con un amplio recibidor y ba\u00f1o. Esta planta es ideal para convertirla en una casa de hu\u00e9spedes, sala de cine, gimnasio o espacio de pr\u00e1ctica.<\/p>\n<p>Caracter\u00edsticas especiales:<\/p>\n<p>Garaje para cuatro coches<br \/>\nAire acondicionado split<br \/>\nDoble acristalamiento<br \/>\nGas natural<br \/>\nArmarios empotrados<br \/>\nAmplias terrazas con vistas fant\u00e1sticas<\/p>\n<p>Este Chalet El Planet Benidorm combina lujo, espacio y funcionalidad en una ubicaci\u00f3n privilegiada en Benidorm. El animado centro, con sus tiendas, restaurantes y vida nocturna, est\u00e1 a pocos pasos, mientras que la famosa Playa de Levante se encuentra a tan solo 4 km. El aeropuerto de Alicante est\u00e1 a unos 60 km.<\/p>\n<p>Si est\u00e1 realmente interesado en este Chalet El Planet Benidorm, estaremos encantados de que se ponga en contacto con nosotros. Tambi\u00e9n puede concertar una visita.<\/p>\n<p><em>El precio con nosotros por el mismo objeto nunca ser\u00e1 m\u00e1s que el de nuestros colegas. Lo que puede ser diferente es la liquidaci\u00f3n de la venta y ayudar por adelantado y luego en la obtenci\u00f3n de los documentos y permisos correctos, etc.<\/em><\/p>\n<p><em>Nuestra especialidad es nuestro m\u00e9todo de trabajo. Queremos guiarte de la A a la Z con el proceso de compra, y solo estamos listos cuando est\u00e9s 100% satisfecho. Antes de que pueda proceder a la compra, primero se deben organizar muchos asuntos perif\u00e9ricos. Tampoco termina con nosotros despu\u00e9s de firmar con el notario, pero somos y seguimos siendo su punto de contacto para futuras preguntas. Por favor, lea tambi\u00e9n la informaci\u00f3n\u00a0<a href=\"https:\/\/inmosolycasas.com\/es\/obre-agencia-inmobiliaria-costa-blanca\/\" target=\"_blank\" rel=\"noopener\">sobre nosotros<\/a>\u00a0\u00a0o uno de nuestros\u00a0<a href=\"https:\/\/inmosolycasas.com\/es\/blog\/\" target=\"_blank\" rel=\"noopener\">blogs<\/a>\u00a0sobre la compra de una casa.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Wikipedia:\u00a0<b>Benidorm<\/b>\u00a0es una ciudad y municipio\u00a0<a title=\"Espa\u00f1a\" href=\"https:\/\/es.wikipedia.org\/wiki\/Espa%C3%B1a\" target=\"_blank\" rel=\"noopener\">espa\u00f1ol<\/a>\u00a0de la\u00a0<a title=\"Provincia de Alicante\" href=\"https:\/\/es.wikipedia.org\/wiki\/Provincia_de_Alicante\" target=\"_blank\" rel=\"noopener\">provincia de Alicante<\/a>, en la\u00a0<a title=\"Comunidad Valenciana\" href=\"https:\/\/es.wikipedia.org\/wiki\/Comunidad_Valenciana\" target=\"_blank\" rel=\"noopener\">Comunidad Valenciana<\/a>. Est\u00e1 situada a orillas del\u00a0<a title=\"Mar Mediterr\u00e1neo\" href=\"https:\/\/es.wikipedia.org\/wiki\/Mar_Mediterr%C3%A1neo\" target=\"_blank\" rel=\"noopener\">mar Mediterr\u00e1neo<\/a>, en la\u00a0<a title=\"Comarca\" href=\"https:\/\/es.wikipedia.org\/wiki\/Comarca\" target=\"_blank\" rel=\"noopener\">comarca<\/a>\u00a0de la\u00a0<a title=\"Marina Baja\" href=\"https:\/\/es.wikipedia.org\/wiki\/Marina_Baja\" target=\"_blank\" rel=\"noopener\">Marina Baja<\/a>, de la que es su municipio m\u00e1s denso y poblado con una densidad de 1792\u00a0hab\/km\u00b2 y 70\u00a0450 habitantes en 2020 seg\u00fan el\u00a0<a class=\"mw-redirect\" title=\"Instituto Nacional de Estad\u00edstica de Espa\u00f1a\" href=\"https:\/\/es.wikipedia.org\/wiki\/Instituto_Nacional_de_Estad%C3%ADstica_de_Espa%C3%B1a\" target=\"_blank\" rel=\"noopener\">INE<\/a>.<sup id=\"cite_ref-3\" class=\"reference separada\"><\/sup>Es la capital tur\u00edstica de la\u00a0<a title=\"Comunidad Valenciana\" href=\"https:\/\/es.wikipedia.org\/wiki\/Comunidad_Valenciana\" target=\"_blank\" rel=\"noopener\">Comunidad Valenciana<\/a>.<sup id=\"cite_ref-d25f4ffe_4-0\" class=\"reference separada\"><\/sup>\u200b<\/p>\n<p>Conocida como la \u00ab<a title=\"Nueva York\" href=\"https:\/\/es.wikipedia.org\/wiki\/Nueva_York\" target=\"_blank\" rel=\"noopener\">Nueva York<\/a>\u00a0del\u00a0<a class=\"mw-redirect\" title=\"Mediterr\u00e1neo\" href=\"https:\/\/es.wikipedia.org\/wiki\/Mediterr%C3%A1neo\" target=\"_blank\" rel=\"noopener\">Mediterr\u00e1neo<\/a>\u00bb,<sup id=\"cite_ref-5\" class=\"reference separada\"><\/sup>\u00a0Benidorm es la ciudad con m\u00e1s rascacielos de\u00a0<a title=\"Espa\u00f1a\" href=\"https:\/\/es.wikipedia.org\/wiki\/Espa%C3%B1a\" target=\"_blank\" rel=\"noopener\">Espa\u00f1a<\/a>,\u00a0<sup id=\"cite_ref-6\" class=\"reference separada\"><\/sup>la ciudad con m\u00e1s rascacielos por habitante del mundo\u00a0<sup id=\"cite_ref-7\" class=\"reference separada\"><\/sup>y la segunda ciudad con m\u00e1s rascacielos por metro cuadrado del mundo, solo detr\u00e1s de\u00a0<a title=\"Nueva York\" href=\"https:\/\/es.wikipedia.org\/wiki\/Nueva_York\" target=\"_blank\" rel=\"noopener\">Nueva York<\/a>.<sup id=\"cite_ref-8\" class=\"reference separada\"><\/sup>\u200b<\/p>\n<p>Se trata de uno de los destinos tur\u00edsticos m\u00e1s importantes y conocidos de\u00a0<a title=\"Espa\u00f1a\" href=\"https:\/\/es.wikipedia.org\/wiki\/Espa%C3%B1a\" target=\"_blank\" rel=\"noopener\">Espa\u00f1a<\/a>\u00a0y de todo el\u00a0<a title=\"Mar Mediterr\u00e1neo\" href=\"https:\/\/es.wikipedia.org\/wiki\/Mar_Mediterr%C3%A1neo\" target=\"_blank\" rel=\"noopener\">Mediterr\u00e1neo<\/a>\u00a0gracias a sus playas y su vida nocturna, llegando a alcanzar los 400\u00a0000 habitantes en verano. No en vano, Benidorm es la tercera ciudad con m\u00e1s plazas hoteleras de Espa\u00f1a tras\u00a0<a title=\"Madrid\" href=\"https:\/\/es.wikipedia.org\/wiki\/Madrid\" target=\"_blank\" rel=\"noopener\">Madrid<\/a>\u00a0y\u00a0<a title=\"Barcelona\" href=\"https:\/\/es.wikipedia.org\/wiki\/Barcelona\" target=\"_blank\" rel=\"noopener\">Barcelona<\/a>.\u200b Benidorm es la primera ciudad espa\u00f1ola en recibir el certificado de Destino Tur\u00edstico Inteligente,<sup id=\"cite_ref-9\" class=\"reference separada\"><a href=\"https:\/\/es.wikipedia.org\/wiki\/Benidorm#cite_note-9\">9<\/a><\/sup>\u200b otorgado por el Instituto para la Calidad Tur\u00edstica de Espa\u00f1a (ICTE) gracias a la innovaci\u00f3n, accesibilidad, transformaci\u00f3n digital y su modelo vertical que permite un mejor aprovechamiento de los recursos.<\/p>\n<p>Tanto en verano como en invierno el clima en Benidorm es agradable, si no c\u00e1lido. Debido a las monta\u00f1as detr\u00e1s de la ciudad, el mal tiempo a menudo no llega a Benidorm. Benidorm es una de las zonas de playa m\u00e1s secas de\u00a0<a href=\"https:\/\/nl.wikipedia.org\/wiki\/Europa_(werelddeel)\" target=\"_blank\" rel=\"noopener\">Europa<\/a>.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" class=\"alignnone wp-image-79420 size-large\" src=\"https:\/\/inmosolycasas.com\/wp-content\/uploads\/2022\/08\/Alicante-Playa-de-levante-6-1024x280.jpeg\" alt=\"Route Alicante-Playa de levante\" width=\"1024\" height=\"280\" srcset=\"https:\/\/inmosolycasas.com\/wp-content\/uploads\/2022\/08\/Alicante-Playa-de-levante-6-1024x280.jpeg 1024w, https:\/\/inmosolycasas.com\/wp-content\/uploads\/2022\/08\/Alicante-Playa-de-levante-6-300x82.jpeg 300w, https:\/\/inmosolycasas.com\/wp-content\/uploads\/2022\/08\/Alicante-Playa-de-levante-6-768x210.jpeg 768w, https:\/\/inmosolycasas.com\/wp-content\/uploads\/2022\/08\/Alicante-Playa-de-levante-6-1536x420.jpeg 1536w, https:\/\/inmosolycasas.com\/wp-content\/uploads\/2022\/08\/Alicante-Playa-de-levante-6-2048x560.jpeg 2048w, https:\/\/inmosolycasas.com\/wp-content\/uploads\/2022\/08\/Alicante-Playa-de-levante-6-496x136.jpeg 496w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p dir=\"auto\">\n","protected":false},"excerpt":{"rendered":"<p>Chalet El Planet Benidorm Esta exclusiva propiedad cuenta con una superficie habitable de 982 m\u00b2 en una generosa parcela de 2.618 m\u00b2. El precioso jard\u00edn incluye \u00e1rboles frutales, un peque\u00f1o huerto y una espaciosa piscina, ideal para relajarse y disfrutar del aire libre. Disfrute del lujo viviendo en esta imponente villa con impresionantes vistas al [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":122922,"parent":0,"menu_order":0,"template":"","property_type":[207,218],"property_status":[496],"property_feature":[527,1404,449,412,456,461,407,409,417,758,450,906,937,890,1000,790,728,923,948,408,713,769,632,912,405,403,406,404,959],"property_label":[811,483],"property_state":[830],"property_city":[1141],"property_area":[],"property_meta":{"houzez_geolocation_lat":["38.625642626928"],"houzez_geolocation_long":["-0.024312697533299"],"_wpml_word_count":["{\"total\":745,\"to_translate\":{\"en\":745,\"es\":745}}"],"_wpml_media_featured":["1"],"_wpml_media_duplicate":["1"],"_yoast_wpseo_focuskw":["Chalet El planet Benidorm"],"_yoast_wpseo_metadesc":["Chalet El planet Benidorm 7 dormitorios, 6 ba\u00f1os, 982 m\u00b2 de puro lujo. Piscina, amplio jard\u00edn, vistas panor\u00e1micas a Benidorm y al mar."],"_yoast_wpseo_linkdex":["82"],"_yoast_wpseo_content_score":["30"],"_yoast_wpseo_estimated-reading-time-minutes":["4"],"fave_property_price":["1635000"],"fave_property_size":["982"],"fave_property_land":["2618"],"fave_property_bedrooms":["7"],"fave_property_bathrooms":["6"],"fave_property_garage":["1"],"fave_property_year":["2000"],"fave_property_id":["CH-BEN-01"],"fave_property_map":["1"],"fave_property_location":["38.625642626928,-0.024312697533299,15"],"fave_property_map_street_view":["hide"],"_yoast_wpseo_primary_property_type":["164"],"_yoast_wpseo_primary_property_status":["121"],"_yoast_wpseo_primary_property_feature":["179"],"_yoast_wpseo_primary_property_label":["128"],"_yoast_wpseo_primary_property_state":["51"],"_yoast_wpseo_primary_property_city":["515"],"_monsterinsights_sitenote_active":["0"],"houzez_total_property_views":["32"],"houzez_views_by_date":["a:12:{s:10:\"04-20-2026\";i:13;s:10:\"04-21-2026\";i:3;s:10:\"04-22-2026\";i:2;s:10:\"04-25-2026\";i:2;s:10:\"04-26-2026\";i:4;s:10:\"04-28-2026\";i:1;s:10:\"04-29-2026\";i:1;s:10:\"05-06-2026\";i:1;s:10:\"05-07-2026\";i:1;s:10:\"05-09-2026\";i:1;s:10:\"05-11-2026\";i:2;s:10:\"05-13-2026\";i:1;}"],"houzez_recently_viewed":["2026-05-13 18:49:27"],"_edit_lock":["1776674896:3"],"_edit_last":["3"],"fave_property_images":["122922","123042","122910","122943","122940","122916","122919","122925","122928","122913","123036","122934","122937","122946","122949","122952","122955","122958","122961","122964","122967","122970","122973","122976","122979","122982","122985","122988","122931","122991","122994","122997","123000","123003","123006","123009","123012","123015","123018","123021","123024","123027","123030","123033","123039","123045","123048","123051"],"_last_translation_edit_mode":["native-editor"],"fave_featured":["1"],"_thumbnail_id":["122922"]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Chalet El planet Benidorm - Inmo Sol y Casas<\/title>\n<meta name=\"description\" content=\"Chalet El planet Benidorm 7 dormitorios, 6 ba\u00f1os, 982 m\u00b2 de puro lujo. Piscina, amplio jard\u00edn, vistas panor\u00e1micas a Benidorm y al mar.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/inmosolycasas.com\/es\/property\/chalet-el-planet-benidorm\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chalet El planet Benidorm - Inmo Sol y Casas\" \/>\n<meta property=\"og:description\" content=\"Chalet El planet Benidorm 7 dormitorios, 6 ba\u00f1os, 982 m\u00b2 de puro lujo. Piscina, amplio jard\u00edn, vistas panor\u00e1micas a Benidorm y al mar.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/inmosolycasas.com\/es\/property\/chalet-el-planet-benidorm\/\" \/>\n<meta property=\"og:site_name\" content=\"Inmo Sol y Casas\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-20T08:50:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/inmosolycasas.com\/wp-content\/uploads\/2026\/04\/Schermafbeelding-2026-04-20-084735.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"732\" \/>\n\t<meta property=\"og:image:height\" content=\"475\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/inmosolycasas.com\/#organization\",\"name\":\"Casa Galera\",\"url\":\"https:\/\/inmosolycasas.com\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/inmosolycasas.com\/#logo\",\"inLanguage\":\"es\",\"url\":\"https:\/\/inmosolycasas.com\/wp-content\/uploads\/2021\/04\/logo.png\",\"contentUrl\":\"https:\/\/inmosolycasas.com\/wp-content\/uploads\/2021\/04\/logo.png\",\"width\":250,\"height\":83,\"caption\":\"Casa Galera\"},\"image\":{\"@id\":\"https:\/\/inmosolycasas.com\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/inmosolycasas.com\/#website\",\"url\":\"https:\/\/inmosolycasas.com\/\",\"name\":\"Inmo Sol y Casas\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/inmosolycasas.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/inmosolycasas.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/inmosolycasas.com\/es\/property\/chalet-el-planet-benidorm\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"https:\/\/inmosolycasas.com\/wp-content\/uploads\/2026\/04\/Schermafbeelding-2026-04-20-084735.jpg\",\"contentUrl\":\"https:\/\/inmosolycasas.com\/wp-content\/uploads\/2026\/04\/Schermafbeelding-2026-04-20-084735.jpg\",\"width\":732,\"height\":475,\"caption\":\"Villa Chalet El planet Benidorm\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/inmosolycasas.com\/es\/property\/chalet-el-planet-benidorm\/#webpage\",\"url\":\"https:\/\/inmosolycasas.com\/es\/property\/chalet-el-planet-benidorm\/\",\"name\":\"Chalet El planet Benidorm - Inmo Sol y Casas\",\"isPartOf\":{\"@id\":\"https:\/\/inmosolycasas.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/inmosolycasas.com\/es\/property\/chalet-el-planet-benidorm\/#primaryimage\"},\"datePublished\":\"2026-04-20T08:41:26+00:00\",\"dateModified\":\"2026-04-20T08:50:28+00:00\",\"description\":\"Chalet El planet Benidorm 7 dormitorios, 6 ba\u00f1os, 982 m\u00b2 de puro lujo. Piscina, amplio jard\u00edn, vistas panor\u00e1micas a Benidorm y al mar.\",\"breadcrumb\":{\"@id\":\"https:\/\/inmosolycasas.com\/es\/property\/chalet-el-planet-benidorm\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/inmosolycasas.com\/es\/property\/chalet-el-planet-benidorm\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/inmosolycasas.com\/es\/property\/chalet-el-planet-benidorm\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/inmosolycasas.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"eigenschappen\",\"item\":\"https:\/\/inmosolycasas.com\/property\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Chalet El planet Benidorm\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chalet El planet Benidorm - Inmo Sol y Casas","description":"Chalet El planet Benidorm 7 dormitorios, 6 ba\u00f1os, 982 m\u00b2 de puro lujo. Piscina, amplio jard\u00edn, vistas panor\u00e1micas a Benidorm y al mar.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/inmosolycasas.com\/es\/property\/chalet-el-planet-benidorm\/","og_locale":"es_ES","og_type":"article","og_title":"Chalet El planet Benidorm - Inmo Sol y Casas","og_description":"Chalet El planet Benidorm 7 dormitorios, 6 ba\u00f1os, 982 m\u00b2 de puro lujo. Piscina, amplio jard\u00edn, vistas panor\u00e1micas a Benidorm y al mar.","og_url":"https:\/\/inmosolycasas.com\/es\/property\/chalet-el-planet-benidorm\/","og_site_name":"Inmo Sol y Casas","article_modified_time":"2026-04-20T08:50:28+00:00","og_image":[{"width":732,"height":475,"url":"https:\/\/inmosolycasas.com\/wp-content\/uploads\/2026\/04\/Schermafbeelding-2026-04-20-084735.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/inmosolycasas.com\/#organization","name":"Casa Galera","url":"https:\/\/inmosolycasas.com\/","sameAs":[],"logo":{"@type":"ImageObject","@id":"https:\/\/inmosolycasas.com\/#logo","inLanguage":"es","url":"https:\/\/inmosolycasas.com\/wp-content\/uploads\/2021\/04\/logo.png","contentUrl":"https:\/\/inmosolycasas.com\/wp-content\/uploads\/2021\/04\/logo.png","width":250,"height":83,"caption":"Casa Galera"},"image":{"@id":"https:\/\/inmosolycasas.com\/#logo"}},{"@type":"WebSite","@id":"https:\/\/inmosolycasas.com\/#website","url":"https:\/\/inmosolycasas.com\/","name":"Inmo Sol y Casas","description":"","publisher":{"@id":"https:\/\/inmosolycasas.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/inmosolycasas.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"ImageObject","@id":"https:\/\/inmosolycasas.com\/es\/property\/chalet-el-planet-benidorm\/#primaryimage","inLanguage":"es","url":"https:\/\/inmosolycasas.com\/wp-content\/uploads\/2026\/04\/Schermafbeelding-2026-04-20-084735.jpg","contentUrl":"https:\/\/inmosolycasas.com\/wp-content\/uploads\/2026\/04\/Schermafbeelding-2026-04-20-084735.jpg","width":732,"height":475,"caption":"Villa Chalet El planet Benidorm"},{"@type":"WebPage","@id":"https:\/\/inmosolycasas.com\/es\/property\/chalet-el-planet-benidorm\/#webpage","url":"https:\/\/inmosolycasas.com\/es\/property\/chalet-el-planet-benidorm\/","name":"Chalet El planet Benidorm - Inmo Sol y Casas","isPartOf":{"@id":"https:\/\/inmosolycasas.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/inmosolycasas.com\/es\/property\/chalet-el-planet-benidorm\/#primaryimage"},"datePublished":"2026-04-20T08:41:26+00:00","dateModified":"2026-04-20T08:50:28+00:00","description":"Chalet El planet Benidorm 7 dormitorios, 6 ba\u00f1os, 982 m\u00b2 de puro lujo. Piscina, amplio jard\u00edn, vistas panor\u00e1micas a Benidorm y al mar.","breadcrumb":{"@id":"https:\/\/inmosolycasas.com\/es\/property\/chalet-el-planet-benidorm\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/inmosolycasas.com\/es\/property\/chalet-el-planet-benidorm\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/inmosolycasas.com\/es\/property\/chalet-el-planet-benidorm\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/inmosolycasas.com\/es\/"},{"@type":"ListItem","position":2,"name":"eigenschappen","item":"https:\/\/inmosolycasas.com\/property\/"},{"@type":"ListItem","position":3,"name":"Chalet El planet Benidorm"}]}]}},"_links":{"self":[{"href":"https:\/\/inmosolycasas.com\/es\/wp-json\/wp\/v2\/properties\/123058"}],"collection":[{"href":"https:\/\/inmosolycasas.com\/es\/wp-json\/wp\/v2\/properties"}],"about":[{"href":"https:\/\/inmosolycasas.com\/es\/wp-json\/wp\/v2\/types\/property"}],"author":[{"embeddable":true,"href":"https:\/\/inmosolycasas.com\/es\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":3,"href":"https:\/\/inmosolycasas.com\/es\/wp-json\/wp\/v2\/properties\/123058\/revisions"}],"predecessor-version":[{"id":123065,"href":"https:\/\/inmosolycasas.com\/es\/wp-json\/wp\/v2\/properties\/123058\/revisions\/123065"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/inmosolycasas.com\/es\/wp-json\/wp\/v2\/media\/122922"}],"wp:attachment":[{"href":"https:\/\/inmosolycasas.com\/es\/wp-json\/wp\/v2\/media?parent=123058"}],"wp:term":[{"taxonomy":"property_type","embeddable":true,"href":"https:\/\/inmosolycasas.com\/es\/wp-json\/wp\/v2\/property_type?post=123058"},{"taxonomy":"property_status","embeddable":true,"href":"https:\/\/inmosolycasas.com\/es\/wp-json\/wp\/v2\/property_status?post=123058"},{"taxonomy":"property_feature","embeddable":true,"href":"https:\/\/inmosolycasas.com\/es\/wp-json\/wp\/v2\/property_feature?post=123058"},{"taxonomy":"property_label","embeddable":true,"href":"https:\/\/inmosolycasas.com\/es\/wp-json\/wp\/v2\/property_label?post=123058"},{"taxonomy":"property_state","embeddable":true,"href":"https:\/\/inmosolycasas.com\/es\/wp-json\/wp\/v2\/property_state?post=123058"},{"taxonomy":"property_city","embeddable":true,"href":"https:\/\/inmosolycasas.com\/es\/wp-json\/wp\/v2\/property_city?post=123058"},{"taxonomy":"property_area","embeddable":true,"href":"https:\/\/inmosolycasas.com\/es\/wp-json\/wp\/v2\/property_area?post=123058"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}