
{"id":73832,"date":"2022-06-15T07:43:35","date_gmt":"2022-06-15T05:43:35","guid":{"rendered":"https:\/\/inmosolycasas.com\/?post_type=property&#038;p=73832"},"modified":"2022-07-27T08:29:03","modified_gmt":"2022-07-27T06:29:03","slug":"venta-finca-hipica-escuela-de-equitacion-elche","status":"publish","type":"property","link":"https:\/\/inmosolycasas.com\/es\/property\/venta-finca-hipica-escuela-de-equitacion-elche\/","title":{"rendered":"Venta Finca Hipica Escuela de Equitaci\u00f3n"},"content":{"rendered":"<p>Venta Finca Hipica Escuela de Equitaci\u00f3n<\/p>\n<p>NAVE PRINCIPAL<br \/>\n*27 boxes (3,5&#215;3)<br \/>\n* 2 guadarn\u00e9s grandes<br \/>\n* 2 vestuarios (y wc) 1 de chico y 1 de chicas grandes<br \/>\nPADOOCK<br \/>\n*18 Padoock exteriores parte con techado, comedero y bebedero autom\u00e1tico<br \/>\nCERCAS<br \/>\n* 2 cercas, 1 donde est\u00e1n las yeguas o caballos de clases sueltos tambi\u00e9n hay 7 parideras un corral 150metros junto a una manga para potros y box grande y otra donde hay 30 boxes port\u00e1tiles y 12 parideras de 4&#215;5 y un potrero y terreno para aparcamientos para concursos (en la misma Corraleta) (TODAS PARIDERAS (bebederos y comederos) y todo box techado<br \/>\n1 PAJAR (250m2)<br \/>\nPISTAS Finca Hipica<br \/>\n* pista de salto de 5.137 m2 con riego autom\u00e1tico y arena de s\u00edlice<br \/>\n*2 pistas de doma reglamentaria juntas 2.400 m2 ( preparada para hacerla cubierta, cimentaciones&#8230;) tambi\u00e9n con riego autom\u00e1tico y arena de playa<br \/>\n*1 pista redonda para potrear 15m<br \/>\n*1 pista cuadrada 20&#215;20 m<br \/>\nANDADOR 8 caballos con interior pista redonda<br \/>\nRESTAURANTE LA H\u00cdPICA<br \/>\nRestaurante con 320m2, preparado para 120 comensales, cocina grande con barbacoa, servidos de se\u00f1ora y caballeros<br \/>\nPARTE DE ABAJO<br \/>\n10.000mtros divididos en 3 cercados en cada uno de ellos una manga<br \/>\n1 BALSA de unos 420.000 L<br \/>\n2 POZOS<br \/>\n+AGUA DE RIEGO<br \/>\n2 ALJIBES<br \/>\nCASICA de madera de 5&#215;5<br \/>\nY oficina<\/p>\n<p>Venta Finca Hipica Escuela de Equitaci\u00f3n<\/p>\n<p>Venta Finca Hipica Escuela de Equitaci\u00f3n<\/p>\n<p><em>Nuestra especialidad es nuestro m\u00e9todo de trabajo. Queremos guiarte de la A a la Z con el proceso de compra, y solo estamos listos cuando est\u00e9s 100% satisfecho. Antes de que pueda proceder a la compra, primero se deben organizar muchos asuntos perif\u00e9ricos. Tampoco termina con nosotros despu\u00e9s de firmar con el notario, pero somos y seguimos siendo su punto de contacto para futuras preguntas. Por favor, lea tambi\u00e9n la informaci\u00f3n\u00a0<a href=\"https:\/\/inmosolycasas.com\/es\/obre-agencia-inmobiliaria-costa-blanca\/\" target=\"_blank\" rel=\"noopener\">sobre nosotros<\/a>\u00a0\u00a0o uno de nuestros\u00a0<a href=\"https:\/\/inmosolycasas.com\/es\/blog\/\" target=\"_blank\" rel=\"noopener\">blogs<\/a>\u00a0sobre la compra de una casa.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Wikipedia:<b>\u00a0Elche<\/b><sup id=\"cite_ref-4\" class=\"reference separada\"><\/sup>\u200b (cooficialmente en\u00a0<a title=\"Idioma valenciano\" href=\"https:\/\/es.wikipedia.org\/wiki\/Idioma_valenciano\" target=\"_blank\" rel=\"noopener\">valenciano<\/a>\u00a0<i>Elx<\/i>,\u00a0<small>AFI:<\/small>)<sup id=\"cite_ref-5\" class=\"reference separada\"><a href=\"https:\/\/es.wikipedia.org\/wiki\/Elche#cite_note-5\">5<\/a><\/sup>\u200b es una ciudad y un municipio de\u00a0<a title=\"Espa\u00f1a\" href=\"https:\/\/es.wikipedia.org\/wiki\/Espa%C3%B1a\" target=\"_blank\" rel=\"noopener\">Espa\u00f1a<\/a>\u00a0situado en la\u00a0<a title=\"Provincia de Alicante\" href=\"https:\/\/es.wikipedia.org\/wiki\/Provincia_de_Alicante\" target=\"_blank\" rel=\"noopener\">provincia de Alicante<\/a>, en la\u00a0<a title=\"Comunidad Valenciana\" href=\"https:\/\/es.wikipedia.org\/wiki\/Comunidad_Valenciana\" target=\"_blank\" rel=\"noopener\">Comunidad Valenciana<\/a>. Capital del\u00a0<a title=\"Bajo Vinalop\u00f3\" href=\"https:\/\/es.wikipedia.org\/wiki\/Bajo_Vinalop%C3%B3\" target=\"_blank\" rel=\"noopener\">Bajo Vinalop\u00f3<\/a>, el municipio cuenta con 234\u00a0765 habitantes (<a title=\"Instituto Nacional de Estad\u00edstica (Espa\u00f1a)\" href=\"https:\/\/es.wikipedia.org\/wiki\/Instituto_Nacional_de_Estad%C3%ADstica_(Espa%C3%B1a)\" target=\"_blank\" rel=\"noopener\">INE<\/a>\u00a02020), siendo la poblaci\u00f3n de su casco urbano de 190\u00a0696 habitantes (INE 2019). Es, de esta forma, la segunda ciudad m\u00e1s poblada de la provincia de Alicante y la tercera de la Comunidad Valenciana, la\u00a0<a title=\"Anexo:Municipios de Espa\u00f1a por poblaci\u00f3n\" href=\"https:\/\/es.wikipedia.org\/wiki\/Anexo:Municipios_de_Espa%C3%B1a_por_poblaci%C3%B3n\" target=\"_blank\" rel=\"noopener\">decimonovena de Espa\u00f1a<\/a>\u00a0y la cuarta mayor ciudad del pa\u00eds sin rango de capital de provincia, desde el punto de vista de la poblaci\u00f3n compacta, por detr\u00e1s de\u00a0<a title=\"Vigo\" href=\"https:\/\/es.wikipedia.org\/wiki\/Vigo\" target=\"_blank\" rel=\"noopener\">Vigo<\/a>,\u00a0<a title=\"Gij\u00f3n\" href=\"https:\/\/es.wikipedia.org\/wiki\/Gij%C3%B3n\" target=\"_blank\" rel=\"noopener\">Gij\u00f3n<\/a>\u00a0y\u00a0<a title=\"Hospitalet de Llobregat\" href=\"https:\/\/es.wikipedia.org\/wiki\/Hospitalet_de_Llobregat\" target=\"_blank\" rel=\"noopener\">Hospitalet de Llobregat<\/a>. El\u00a0<a title=\"\u00c1rea metropolitana de Alicante-Elche\" href=\"https:\/\/es.wikipedia.org\/wiki\/%C3%81rea_metropolitana_de_Alicante-Elche\" target=\"_blank\" rel=\"noopener\">\u00e1rea metropolitana de Alicante-Elche<\/a>, que la agrupa con la conurbaci\u00f3n de\u00a0<a title=\"Alicante\" href=\"https:\/\/es.wikipedia.org\/wiki\/Alicante\" target=\"_blank\" rel=\"noopener\">Alicante<\/a>\u2013<a title=\"San Vicente del Raspeig\" href=\"https:\/\/es.wikipedia.org\/wiki\/San_Vicente_del_Raspeig\" target=\"_blank\" rel=\"noopener\">San Vicente del Raspeig<\/a>\u2013<a title=\"San Juan de Alicante\" href=\"https:\/\/es.wikipedia.org\/wiki\/San_Juan_de_Alicante\" target=\"_blank\" rel=\"noopener\">San Juan de Alicante<\/a>\u00a0y con las localidades pr\u00f3ximas de\u00a0<a title=\"Santa Pola\" href=\"https:\/\/es.wikipedia.org\/wiki\/Santa_Pola\" target=\"_blank\" rel=\"noopener\">Santa Pola<\/a>\u00a0y\u00a0<a title=\"Crevillente\" href=\"https:\/\/es.wikipedia.org\/wiki\/Crevillente\" target=\"_blank\" rel=\"noopener\">Crevillente<\/a>, es la\u00a0<a title=\"Anexo:\u00c1reas metropolitanas de Espa\u00f1a\" href=\"https:\/\/es.wikipedia.org\/wiki\/Anexo:%C3%81reas_metropolitanas_de_Espa%C3%B1a\" target=\"_blank\" rel=\"noopener\">novena m\u00e1s poblada de Espa\u00f1a<\/a>, con unos 700\u00a0000 habitantes.<\/p>\n<p>En el siglo\u00a0v\u00a0a.\u00a0C. fue fundada la ciudad\u00a0<a title=\"Iberos\" href=\"https:\/\/es.wikipedia.org\/wiki\/Iberos\" target=\"_blank\" rel=\"noopener\">ibera<\/a>\u00a0de Helike. Con la llegada de los\u00a0<a title=\"Imperio romano\" href=\"https:\/\/es.wikipedia.org\/wiki\/Imperio_romano\" target=\"_blank\" rel=\"noopener\">romanos<\/a>, se desarroll\u00f3 un proceso de formaci\u00f3n de una colonia poblada con veteranos de las\u00a0<a title=\"Guerras c\u00e1ntabras\" href=\"https:\/\/es.wikipedia.org\/wiki\/Guerras_c%C3%A1ntabras\" target=\"_blank\" rel=\"noopener\">guerras c\u00e1ntabras<\/a>, que pasar\u00eda a llamarse Colonia Iulia Illici Augusta, en torno al a\u00f1o\u00a0<a title=\"26 a. C.\" href=\"https:\/\/es.wikipedia.org\/wiki\/26_a._C.\" target=\"_blank\" rel=\"noopener\">26\u00a0a.\u00a0C.<\/a>. Bajo el dominio\u00a0<a title=\"Conquista musulmana de la pen\u00ednsula ib\u00e9rica\" href=\"https:\/\/es.wikipedia.org\/wiki\/Conquista_musulmana_de_la_pen%C3%ADnsula_ib%C3%A9rica\" target=\"_blank\" rel=\"noopener\">musulm\u00e1n<\/a>\u00a0en la\u00a0<a title=\"Historia medieval de Espa\u00f1a\" href=\"https:\/\/es.wikipedia.org\/wiki\/Historia_medieval_de_Espa%C3%B1a\" target=\"_blank\" rel=\"noopener\">Edad Media<\/a>, la ciudad se estableci\u00f3 en su emplazamiento actual. A ra\u00edz de la\u00a0<a title=\"Reconquista\" href=\"https:\/\/es.wikipedia.org\/wiki\/Reconquista\" target=\"_blank\" rel=\"noopener\">reconquista cristiana<\/a>, alrededor del a\u00f1o 1250, la ciudad pas\u00f3 a la\u00a0<a title=\"Corona de Castilla\" href=\"https:\/\/es.wikipedia.org\/wiki\/Corona_de_Castilla\" target=\"_blank\" rel=\"noopener\">Corona de Castilla<\/a>. En el a\u00f1o 1265, los musulmanes fueron expulsados de la ciudad tras una rebeli\u00f3n y, en 1305, Elche fue cedida al\u00a0<a title=\"Reino de Valencia\" href=\"https:\/\/es.wikipedia.org\/wiki\/Reino_de_Valencia\" target=\"_blank\" rel=\"noopener\">Reino de Valencia<\/a>. Fue durante el reinado de\u00a0<a title=\"Amadeo I de Espa\u00f1a\" href=\"https:\/\/es.wikipedia.org\/wiki\/Amadeo_I_de_Espa%C3%B1a\" target=\"_blank\" rel=\"noopener\">Amadeo I<\/a>\u00a0en 1871, cuando el monarca le otorg\u00f3 el t\u00edtulo de ciudad. Durante los a\u00f1os 1960 y 1970, la ciudad experiment\u00f3 un fuerte aumento de poblaci\u00f3n ligado a la\u00a0<a title=\"Industrializaci\u00f3n\" href=\"https:\/\/es.wikipedia.org\/wiki\/Industrializaci%C3%B3n\" target=\"_blank\" rel=\"noopener\">industrializaci\u00f3n<\/a>, que convertir\u00eda a Elche en uno de los principales productores de\u00a0<a title=\"Calzado\" href=\"https:\/\/es.wikipedia.org\/wiki\/Calzado\" target=\"_blank\" rel=\"noopener\">calzado<\/a>\u00a0de\u00a0<a title=\"Europa\" href=\"https:\/\/es.wikipedia.org\/wiki\/Europa\" target=\"_blank\" rel=\"noopener\">Europa<\/a>,\u00a0<sup id=\"cite_ref-calzado_6-0\" class=\"reference separada\"><\/sup>dando origen a marcas internacionales como\u00a0<a title=\"Pura L\u00f3pez\" href=\"https:\/\/es.wikipedia.org\/wiki\/Pura_L%C3%B3pez\" target=\"_blank\" rel=\"noopener\">Pura L\u00f3pez<\/a>,\u00a0<a title=\"Panama Jack\" href=\"https:\/\/es.wikipedia.org\/wiki\/Panama_Jack\" target=\"_blank\" rel=\"noopener\">Panama Jack<\/a>\u00a0o\u00a0<a title=\"Kelme\" href=\"https:\/\/es.wikipedia.org\/wiki\/Kelme\" target=\"_blank\" rel=\"noopener\">Kelme<\/a>.<\/p>\n<p>El\u00a0<a title=\"Palmeral de Elche\" href=\"https:\/\/es.wikipedia.org\/wiki\/Palmeral_de_Elche\" target=\"_blank\" rel=\"noopener\">Palmeral<\/a>\u00a0y el\u00a0<a title=\"Misterio de Elche\" href=\"https:\/\/es.wikipedia.org\/wiki\/Misterio_de_Elche\" target=\"_blank\" rel=\"noopener\">Misterio de Elche<\/a>\u00a0est\u00e1n declarados\u00a0<a title=\"Patrimonio de la Humanidad\" href=\"https:\/\/es.wikipedia.org\/wiki\/Patrimonio_de_la_Humanidad\" target=\"_blank\" rel=\"noopener\">Patrimonio de la Humanidad<\/a>\u00a0y\u00a0<a title=\"Anexo:Obras Maestras del Patrimonio Oral e Intangible de la Humanidad\" href=\"https:\/\/es.wikipedia.org\/wiki\/Anexo:Obras_Maestras_del_Patrimonio_Oral_e_Intangible_de_la_Humanidad\" target=\"_blank\" rel=\"noopener\">Obra Maestra del Patrimonio Oral e Intangible de la Humanidad<\/a>, respectivamente, por la\u00a0<a title=\"Unesco\" href=\"https:\/\/es.wikipedia.org\/wiki\/Unesco\" target=\"_blank\" rel=\"noopener\">Unesco<\/a>. Son s\u00edmbolos de identidad y principales atractivos tur\u00edsticos de esta ciudad de tradici\u00f3n industrial.<\/p>\n<p>Elche es el \u00fanico lugar del mundo en el que la elaboraci\u00f3n artesanal de la palma blanca persiste. El ayuntamiento env\u00eda anualmente para la\u00a0<a title=\"Semana Santa\" href=\"https:\/\/es.wikipedia.org\/wiki\/Semana_Santa\" target=\"_blank\" rel=\"noopener\">Semana Santa<\/a>\u00a0las palmas blancas a autoridades eclesi\u00e1sticas y pol\u00edticas, como a los\u00a0<a title=\"Rey de Espa\u00f1a\" href=\"https:\/\/es.wikipedia.org\/wiki\/Rey_de_Espa%C3%B1a\" target=\"_blank\" rel=\"noopener\">reyes de Espa\u00f1a<\/a>, el\u00a0<a title=\"Papa\" href=\"https:\/\/es.wikipedia.org\/wiki\/Papa\" target=\"_blank\" rel=\"noopener\">papa<\/a>\u00a0o el\u00a0<a title=\"Presidente del Gobierno de Espa\u00f1a\" href=\"https:\/\/es.wikipedia.org\/wiki\/Presidente_del_Gobierno_de_Espa%C3%B1a\" target=\"_blank\" rel=\"noopener\">presidente del Gobierno<\/a>.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" class=\"alignnone wp-image-75464 size-large\" src=\"https:\/\/inmosolycasas.com\/wp-content\/uploads\/2022\/06\/Alicante-Elche-3-1024x288.jpeg\" alt=\"Alicante-Elche\" width=\"1024\" height=\"288\" srcset=\"https:\/\/inmosolycasas.com\/wp-content\/uploads\/2022\/06\/Alicante-Elche-3-1024x288.jpeg 1024w, https:\/\/inmosolycasas.com\/wp-content\/uploads\/2022\/06\/Alicante-Elche-3-300x84.jpeg 300w, https:\/\/inmosolycasas.com\/wp-content\/uploads\/2022\/06\/Alicante-Elche-3-768x216.jpeg 768w, https:\/\/inmosolycasas.com\/wp-content\/uploads\/2022\/06\/Alicante-Elche-3-1536x432.jpeg 1536w, https:\/\/inmosolycasas.com\/wp-content\/uploads\/2022\/06\/Alicante-Elche-3-2048x577.jpeg 2048w, https:\/\/inmosolycasas.com\/wp-content\/uploads\/2022\/06\/Alicante-Elche-3-496x140.jpeg 496w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Venta Finca Hipica Escuela de Equitaci\u00f3n NAVE PRINCIPAL *27 boxes (3,5&#215;3) * 2 guadarn\u00e9s grandes * 2 vestuarios (y wc) 1 de chico y 1 de chicas grandes PADOOCK *18 Padoock exteriores parte con techado, comedero y bebedero autom\u00e1tico CERCAS * 2 cercas, 1 donde est\u00e1n las yeguas o caballos de clases sueltos tambi\u00e9n hay [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":73257,"parent":0,"menu_order":0,"template":"","property_type":[],"property_status":[496],"property_feature":[],"property_label":[],"property_state":[830],"property_city":[926],"property_area":[],"property_meta":{"houzez_geolocation_lat":["38.625642626928"],"houzez_geolocation_long":["-0.024312697533299"],"_wpml_word_count":["{\"total\":186,\"to_translate\":{\"en\":186,\"es\":186}}"],"_wpml_media_featured":["1"],"_wpml_media_duplicate":["1"],"_yoast_wpseo_estimated-reading-time-minutes":["4"],"fave_property_map":["1"],"fave_property_location":["38.625642626928,-0.024312697533299,15"],"fave_property_map_street_view":["hide"],"_yoast_wpseo_content_score":["30"],"fave_property_id":["OLC01778"],"_yoast_wpseo_primary_property_state":["51"],"_yoast_wpseo_primary_property_city":["915"],"fave_property_price":["1950000"],"fave_property_land":["47500"],"fave_property_bathrooms":["2"],"fave_property_year":["2000"],"_edit_lock":["1658903250:3"],"_edit_last":["3"],"_last_translation_edit_mode":["native-editor"],"houzez_total_property_views":["1361"],"houzez_views_by_date":["a:61:{s:10:\"06-18-2026\";i:2;s:10:\"06-20-2026\";i:1;s:10:\"06-21-2026\";i:2;s:10:\"06-22-2026\";i:2;s:10:\"06-23-2026\";i:2;s:10:\"06-25-2026\";i:1;s:10:\"06-26-2026\";i:2;s:10:\"06-27-2026\";i:1;s:10:\"06-28-2026\";i:3;s:10:\"06-29-2026\";i:1;s:10:\"06-30-2026\";i:1;s:10:\"07-01-2026\";i:1;s:10:\"07-03-2026\";i:1;s:10:\"07-04-2026\";i:3;s:10:\"07-05-2026\";i:5;s:10:\"07-06-2026\";i:1;s:10:\"07-09-2026\";i:2;s:10:\"07-10-2026\";i:1;s:10:\"07-11-2026\";i:3;s:10:\"07-12-2026\";i:1;s:10:\"07-13-2026\";i:2;s:10:\"07-14-2026\";i:1;s:10:\"07-15-2026\";i:1;s:10:\"07-16-2026\";i:2;s:10:\"07-17-2026\";i:1;s:10:\"07-18-2026\";i:2;s:10:\"07-19-2026\";i:2;s:10:\"07-20-2026\";i:4;s:10:\"07-21-2026\";i:4;s:10:\"07-26-2026\";i:2;s:10:\"07-27-2026\";i:4;s:10:\"07-28-2026\";i:2;s:10:\"07-29-2026\";i:4;s:10:\"07-30-2026\";i:1;s:10:\"08-01-2026\";i:3;s:10:\"08-03-2026\";i:1;s:10:\"08-04-2026\";i:1;s:10:\"08-05-2026\";i:3;s:10:\"08-07-2026\";i:1;s:10:\"08-09-2026\";i:1;s:10:\"08-10-2026\";i:1;s:10:\"08-12-2026\";i:1;s:10:\"08-13-2026\";i:3;s:10:\"08-14-2026\";i:3;s:10:\"08-15-2026\";i:2;s:10:\"08-16-2026\";i:2;s:10:\"08-17-2026\";i:2;s:10:\"08-18-2026\";i:2;s:10:\"08-19-2026\";i:2;s:10:\"08-20-2026\";i:2;s:10:\"08-21-2026\";i:3;s:10:\"08-23-2026\";i:1;s:10:\"08-24-2026\";i:1;s:10:\"08-25-2026\";i:2;s:10:\"08-26-2026\";i:1;s:10:\"08-27-2026\";i:2;s:10:\"08-29-2026\";i:1;s:10:\"08-30-2026\";i:1;s:10:\"08-31-2026\";i:4;s:10:\"09-01-2026\";i:2;s:10:\"09-02-2026\";i:1;}"],"houzez_recently_viewed":["2026-09-02 12:41:51"],"_yoast_wpseo_focuskw":["Venta Finca Hipica"],"_yoast_wpseo_metadesc":["Venta Finca Hipica Escuela de Equitaci\u00f3n en la Costa Blanca en la regi\u00f3n de Elche Alicante Espa\u00f1a. Precio 1.950.000\u20ac"],"_yoast_wpseo_linkdex":["80"],"fave_property_images":["73371","73311","73254","73257","73263","73266","73269","73272","73275","73341","73278","73281","73284","73287","73290","73293","73296","73299","73302","73305","73308","73314","73317","73320","73323","73326","73329","73332","73335","73338","73344","73347","73350","73353","73356","73359","73362","73365","73368","73828"],"fave_featured":["0"],"_thumbnail_id":["73257"]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Venta Finca Hipica Escuela de Equitaci\u00f3n - Inmo Sol y Casas<\/title>\n<meta name=\"description\" content=\"Venta Finca Hipica Escuela de Equitaci\u00f3n en la Costa Blanca en la regi\u00f3n de Elche Alicante Espa\u00f1a. Precio 1.950.000\u20ac\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/inmosolycasas.com\/es\/property\/venta-finca-hipica-escuela-de-equitacion-elche\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Venta Finca Hipica Escuela de Equitaci\u00f3n - Inmo Sol y Casas\" \/>\n<meta property=\"og:description\" content=\"Venta Finca Hipica Escuela de Equitaci\u00f3n en la Costa Blanca en la regi\u00f3n de Elche Alicante Espa\u00f1a. Precio 1.950.000\u20ac\" \/>\n<meta property=\"og:url\" content=\"https:\/\/inmosolycasas.com\/es\/property\/venta-finca-hipica-escuela-de-equitacion-elche\/\" \/>\n<meta property=\"og:site_name\" content=\"Inmo Sol y Casas\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-27T06:29:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/inmosolycasas.com\/wp-content\/uploads\/2022\/06\/foto2-15.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"937\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/inmosolycasas.com\/#organization\",\"name\":\"Casa Galera\",\"url\":\"https:\/\/inmosolycasas.com\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/inmosolycasas.com\/#logo\",\"inLanguage\":\"es\",\"url\":\"https:\/\/inmosolycasas.com\/wp-content\/uploads\/2021\/04\/logo.png\",\"contentUrl\":\"https:\/\/inmosolycasas.com\/wp-content\/uploads\/2021\/04\/logo.png\",\"width\":250,\"height\":83,\"caption\":\"Casa Galera\"},\"image\":{\"@id\":\"https:\/\/inmosolycasas.com\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/inmosolycasas.com\/#website\",\"url\":\"https:\/\/inmosolycasas.com\/\",\"name\":\"Inmo Sol y Casas\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/inmosolycasas.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/inmosolycasas.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/inmosolycasas.com\/es\/property\/venta-finca-hipica-escuela-de-equitacion-elche\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"https:\/\/inmosolycasas.com\/wp-content\/uploads\/2022\/06\/foto2-15.jpg\",\"contentUrl\":\"https:\/\/inmosolycasas.com\/wp-content\/uploads\/2022\/06\/foto2-15.jpg\",\"width\":1400,\"height\":937,\"caption\":\"Venta Finca Hipica Escuela de Equitaci\u00f3n\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/inmosolycasas.com\/es\/property\/venta-finca-hipica-escuela-de-equitacion-elche\/#webpage\",\"url\":\"https:\/\/inmosolycasas.com\/es\/property\/venta-finca-hipica-escuela-de-equitacion-elche\/\",\"name\":\"Venta Finca Hipica Escuela de Equitaci\u00f3n - Inmo Sol y Casas\",\"isPartOf\":{\"@id\":\"https:\/\/inmosolycasas.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/inmosolycasas.com\/es\/property\/venta-finca-hipica-escuela-de-equitacion-elche\/#primaryimage\"},\"datePublished\":\"2022-06-15T05:43:35+00:00\",\"dateModified\":\"2022-07-27T06:29:03+00:00\",\"description\":\"Venta Finca Hipica Escuela de Equitaci\u00f3n en la Costa Blanca en la regi\u00f3n de Elche Alicante Espa\u00f1a. Precio 1.950.000\u20ac\",\"breadcrumb\":{\"@id\":\"https:\/\/inmosolycasas.com\/es\/property\/venta-finca-hipica-escuela-de-equitacion-elche\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/inmosolycasas.com\/es\/property\/venta-finca-hipica-escuela-de-equitacion-elche\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/inmosolycasas.com\/es\/property\/venta-finca-hipica-escuela-de-equitacion-elche\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/inmosolycasas.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"eigenschappen\",\"item\":\"https:\/\/inmosolycasas.com\/property\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Venta Finca Hipica Escuela de Equitaci\u00f3n\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Venta Finca Hipica Escuela de Equitaci\u00f3n - Inmo Sol y Casas","description":"Venta Finca Hipica Escuela de Equitaci\u00f3n en la Costa Blanca en la regi\u00f3n de Elche Alicante Espa\u00f1a. Precio 1.950.000\u20ac","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/inmosolycasas.com\/es\/property\/venta-finca-hipica-escuela-de-equitacion-elche\/","og_locale":"es_ES","og_type":"article","og_title":"Venta Finca Hipica Escuela de Equitaci\u00f3n - Inmo Sol y Casas","og_description":"Venta Finca Hipica Escuela de Equitaci\u00f3n en la Costa Blanca en la regi\u00f3n de Elche Alicante Espa\u00f1a. Precio 1.950.000\u20ac","og_url":"https:\/\/inmosolycasas.com\/es\/property\/venta-finca-hipica-escuela-de-equitacion-elche\/","og_site_name":"Inmo Sol y Casas","article_modified_time":"2022-07-27T06:29:03+00:00","og_image":[{"width":1400,"height":937,"url":"https:\/\/inmosolycasas.com\/wp-content\/uploads\/2022\/06\/foto2-15.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/inmosolycasas.com\/#organization","name":"Casa Galera","url":"https:\/\/inmosolycasas.com\/","sameAs":[],"logo":{"@type":"ImageObject","@id":"https:\/\/inmosolycasas.com\/#logo","inLanguage":"es","url":"https:\/\/inmosolycasas.com\/wp-content\/uploads\/2021\/04\/logo.png","contentUrl":"https:\/\/inmosolycasas.com\/wp-content\/uploads\/2021\/04\/logo.png","width":250,"height":83,"caption":"Casa Galera"},"image":{"@id":"https:\/\/inmosolycasas.com\/#logo"}},{"@type":"WebSite","@id":"https:\/\/inmosolycasas.com\/#website","url":"https:\/\/inmosolycasas.com\/","name":"Inmo Sol y Casas","description":"","publisher":{"@id":"https:\/\/inmosolycasas.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/inmosolycasas.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"ImageObject","@id":"https:\/\/inmosolycasas.com\/es\/property\/venta-finca-hipica-escuela-de-equitacion-elche\/#primaryimage","inLanguage":"es","url":"https:\/\/inmosolycasas.com\/wp-content\/uploads\/2022\/06\/foto2-15.jpg","contentUrl":"https:\/\/inmosolycasas.com\/wp-content\/uploads\/2022\/06\/foto2-15.jpg","width":1400,"height":937,"caption":"Venta Finca Hipica Escuela de Equitaci\u00f3n"},{"@type":"WebPage","@id":"https:\/\/inmosolycasas.com\/es\/property\/venta-finca-hipica-escuela-de-equitacion-elche\/#webpage","url":"https:\/\/inmosolycasas.com\/es\/property\/venta-finca-hipica-escuela-de-equitacion-elche\/","name":"Venta Finca Hipica Escuela de Equitaci\u00f3n - Inmo Sol y Casas","isPartOf":{"@id":"https:\/\/inmosolycasas.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/inmosolycasas.com\/es\/property\/venta-finca-hipica-escuela-de-equitacion-elche\/#primaryimage"},"datePublished":"2022-06-15T05:43:35+00:00","dateModified":"2022-07-27T06:29:03+00:00","description":"Venta Finca Hipica Escuela de Equitaci\u00f3n en la Costa Blanca en la regi\u00f3n de Elche Alicante Espa\u00f1a. Precio 1.950.000\u20ac","breadcrumb":{"@id":"https:\/\/inmosolycasas.com\/es\/property\/venta-finca-hipica-escuela-de-equitacion-elche\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/inmosolycasas.com\/es\/property\/venta-finca-hipica-escuela-de-equitacion-elche\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/inmosolycasas.com\/es\/property\/venta-finca-hipica-escuela-de-equitacion-elche\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/inmosolycasas.com\/es\/"},{"@type":"ListItem","position":2,"name":"eigenschappen","item":"https:\/\/inmosolycasas.com\/property\/"},{"@type":"ListItem","position":3,"name":"Venta Finca Hipica Escuela de Equitaci\u00f3n"}]}]}},"_links":{"self":[{"href":"https:\/\/inmosolycasas.com\/es\/wp-json\/wp\/v2\/properties\/73832"}],"collection":[{"href":"https:\/\/inmosolycasas.com\/es\/wp-json\/wp\/v2\/properties"}],"about":[{"href":"https:\/\/inmosolycasas.com\/es\/wp-json\/wp\/v2\/types\/property"}],"author":[{"embeddable":true,"href":"https:\/\/inmosolycasas.com\/es\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":11,"href":"https:\/\/inmosolycasas.com\/es\/wp-json\/wp\/v2\/properties\/73832\/revisions"}],"predecessor-version":[{"id":78104,"href":"https:\/\/inmosolycasas.com\/es\/wp-json\/wp\/v2\/properties\/73832\/revisions\/78104"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/inmosolycasas.com\/es\/wp-json\/wp\/v2\/media\/73257"}],"wp:attachment":[{"href":"https:\/\/inmosolycasas.com\/es\/wp-json\/wp\/v2\/media?parent=73832"}],"wp:term":[{"taxonomy":"property_type","embeddable":true,"href":"https:\/\/inmosolycasas.com\/es\/wp-json\/wp\/v2\/property_type?post=73832"},{"taxonomy":"property_status","embeddable":true,"href":"https:\/\/inmosolycasas.com\/es\/wp-json\/wp\/v2\/property_status?post=73832"},{"taxonomy":"property_feature","embeddable":true,"href":"https:\/\/inmosolycasas.com\/es\/wp-json\/wp\/v2\/property_feature?post=73832"},{"taxonomy":"property_label","embeddable":true,"href":"https:\/\/inmosolycasas.com\/es\/wp-json\/wp\/v2\/property_label?post=73832"},{"taxonomy":"property_state","embeddable":true,"href":"https:\/\/inmosolycasas.com\/es\/wp-json\/wp\/v2\/property_state?post=73832"},{"taxonomy":"property_city","embeddable":true,"href":"https:\/\/inmosolycasas.com\/es\/wp-json\/wp\/v2\/property_city?post=73832"},{"taxonomy":"property_area","embeddable":true,"href":"https:\/\/inmosolycasas.com\/es\/wp-json\/wp\/v2\/property_area?post=73832"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}